{"id":5094,"date":"2023-04-21T11:03:13","date_gmt":"2023-04-21T11:03:13","guid":{"rendered":"http:\/\/localhost\/?p=5094"},"modified":"2023-05-12T06:41:41","modified_gmt":"2023-05-12T06:41:41","slug":"propuestas-para-trabajar-con-los-canales-en-teams","status":"publish","type":"post","link":"https:\/\/www3.ubu.es\/ubucevblog\/propuestas-para-trabajar-con-los-canales-en-teams\/","title":{"rendered":"Propuestas para trabajar con los canales en Teams"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_5094\" class=\"pvc_stats total_only  \" data-element-id=\"5094\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abLas redes de comunicaci\u00f3n introducen una configuraci\u00f3n tecnol\u00f3gica que potencia un aprendizaje<br>m\u00e1s flexible y, al mismo tiempo, la existencia de nuevos escenarios del aprendizaje\u00bb (Lucero, 2003, p. 3).<\/p>\n\n\n\n<div style=\"height:8px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Dicho esto, la creaci\u00f3n de nuevos escenarios de aprendizaje es fundamental para la innovaci\u00f3n educativa. En la entrada anterior, est\u00e1bamos abordando <a href=\"https:\/\/www3.ubu.es\/ubucevblog\/uso-de-la-funcionalidad-de-canales-en-teams\/\">Uso de la funcionalidad de canales en Teams<\/a>, en esta ocasi\u00f3n estaremos conociendo propuestas educativas para trabajar con los canales en Teams. <\/p>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-374494b2 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path d=\"M448 336v-288C448 21.49 426.5 0 400 0H96C42.98 0 0 42.98 0 96v320c0 53.02 42.98 96 96 96h320c17.67 0 32-14.33 32-31.1c0-11.72-6.607-21.52-16-27.1v-81.36C441.8 362.8 448 350.2 448 336zM143.1 128h192C344.8 128 352 135.2 352 144C352 152.8 344.8 160 336 160H143.1C135.2 160 128 152.8 128 144C128 135.2 135.2 128 143.1 128zM143.1 192h192C344.8 192 352 199.2 352 208C352 216.8 344.8 224 336 224H143.1C135.2 224 128 216.8 128 208C128 199.2 135.2 192 143.1 192zM384 448H96c-17.67 0-32-14.33-32-32c0-17.67 14.33-32 32-32h288V448z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Wiki<\/h3><\/div><p class=\"uagb-ifb-desc\">La creaci\u00f3n de Wiki, es muy \u00fatil para la difusi\u00f3n de conocimientos y trabajos en equipo. Los docentes lo pueden utilizar para que sus alumnos puedan crear contenido en equipo.  <\/p><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Para crear Wiki en Teams tenemos que: <\/p>\n\n\n\n<div class=\"wp-block-uagb-icon-list uagb-block-99851ce1\"><div class=\"uagb-icon-list__wrap\">\n<div class=\"wp-block-uagb-icon-list-child uagb-block-211e036c\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M256 0C114.6 0 0 114.6 0 256c0 141.4 114.6 256 256 256s256-114.6 256-256C512 114.6 397.4 0 256 0zM406.6 278.6l-103.1 103.1c-12.5 12.5-32.75 12.5-45.25 0s-12.5-32.75 0-45.25L306.8 288H128C110.3 288 96 273.7 96 256s14.31-32 32-32h178.8l-49.38-49.38c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l103.1 103.1C414.6 241.3 416 251.1 416 256C416 260.9 414.6 270.7 406.6 278.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">Acceder al canal creado. <\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-3b2787d4\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M256 0C114.6 0 0 114.6 0 256c0 141.4 114.6 256 256 256s256-114.6 256-256C512 114.6 397.4 0 256 0zM406.6 278.6l-103.1 103.1c-12.5 12.5-32.75 12.5-45.25 0s-12.5-32.75 0-45.25L306.8 288H128C110.3 288 96 273.7 96 256s14.31-32 32-32h178.8l-49.38-49.38c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l103.1 103.1C414.6 241.3 416 251.1 416 256C416 260.9 414.6 270.7 406.6 278.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">Agregar Wiki. <\/span><\/div>\n<\/div><\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Crear wiki\" width=\"640\" height=\"480\" src=\"https:\/\/www.youtube.com\/embed\/MIoZnzGUmmc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<div style=\"height:43px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-0545b43c uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 640 512\"><path d=\"M592 0h-384C181.5 0 160 22.25 160 49.63V96c23.42 0 45.1 6.781 63.1 17.81V64h352v288h-64V304c0-8.838-7.164-16-16-16h-96c-8.836 0-16 7.162-16 16V352H287.3c22.07 16.48 39.54 38.5 50.76 64h253.9C618.5 416 640 393.8 640 366.4V49.63C640 22.25 618.5 0 592 0zM160 320c53.02 0 96-42.98 96-96c0-53.02-42.98-96-96-96C106.1 128 64 170.1 64 224C64 277 106.1 320 160 320zM192 352H128c-70.69 0-128 57.31-128 128c0 17.67 14.33 32 32 32h256c17.67 0 32-14.33 32-32C320 409.3 262.7 352 192 352z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Whiteboard<\/h3><\/div><p class=\"uagb-ifb-desc\">Utilizar la pizarra digital Whiteboard puede ser \u00fatil para trabajar de forma colaborativa y creativa. <\/p><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Para utilizar Whiteboard en Teams tenemos que: <\/p>\n\n\n\n<div class=\"wp-block-uagb-icon-list uagb-block-b9a08d10\"><div class=\"uagb-icon-list__wrap\">\n<div class=\"wp-block-uagb-icon-list-child uagb-block-2dd71966\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M256 0C114.6 0 0 114.6 0 256c0 141.4 114.6 256 256 256s256-114.6 256-256C512 114.6 397.4 0 256 0zM406.6 278.6l-103.1 103.1c-12.5 12.5-32.75 12.5-45.25 0s-12.5-32.75 0-45.25L306.8 288H128C110.3 288 96 273.7 96 256s14.31-32 32-32h178.8l-49.38-49.38c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l103.1 103.1C414.6 241.3 416 251.1 416 256C416 260.9 414.6 270.7 406.6 278.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">Acceder al canal creado. <\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-5d47adda\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M256 0C114.6 0 0 114.6 0 256c0 141.4 114.6 256 256 256s256-114.6 256-256C512 114.6 397.4 0 256 0zM406.6 278.6l-103.1 103.1c-12.5 12.5-32.75 12.5-45.25 0s-12.5-32.75 0-45.25L306.8 288H128C110.3 288 96 273.7 96 256s14.31-32 32-32h178.8l-49.38-49.38c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l103.1 103.1C414.6 241.3 416 251.1 416 256C416 260.9 414.6 270.7 406.6 278.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">Agregar Whiteboard. <\/span><\/div>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Whiteboard en canales\" width=\"640\" height=\"480\" src=\"https:\/\/www.youtube.com\/embed\/t9GLKTqdVj4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<div style=\"height:49px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-96acbb1b uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 384 512\"><path d=\"M256 0v128h128L256 0zM288 256H96v64h192V256zM224 128L224 0H48C21.49 0 0 21.49 0 48v416C0 490.5 21.49 512 48 512h288c26.51 0 48-21.49 48-48V160h-127.1C238.3 160 224 145.7 224 128zM64 72C64 67.63 67.63 64 72 64h80C156.4 64 160 67.63 160 72v16C160 92.38 156.4 96 152 96h-80C67.63 96 64 92.38 64 88V72zM64 136C64 131.6 67.63 128 72 128h80C156.4 128 160 131.6 160 136v16C160 156.4 156.4 160 152 160h-80C67.63 160 64 156.4 64 152V136zM320 440c0 4.375-3.625 8-8 8h-80C227.6 448 224 444.4 224 440v-16c0-4.375 3.625-8 8-8h80c4.375 0 8 3.625 8 8V440zM320 240v96c0 8.875-7.125 16-16 16h-224C71.13 352 64 344.9 64 336v-96C64 231.1 71.13 224 80 224h224C312.9 224 320 231.1 320 240z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Archivos<\/h3><\/div><p class=\"uagb-ifb-desc\">Crear archivos y almacenarlos en diferentes carpetas puede ser de utilidad para favorecer el trabajado online y hacer correcciones de lo mismos. Estas carpetas se pueden sincronizar con OneDrive.<\/p><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Para crear archivos tenemos que: <\/p>\n\n\n\n<div class=\"wp-block-uagb-icon-list uagb-block-175a5ce7\"><div class=\"uagb-icon-list__wrap\">\n<div class=\"wp-block-uagb-icon-list-child uagb-block-04ff6b66\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M256 0C114.6 0 0 114.6 0 256c0 141.4 114.6 256 256 256s256-114.6 256-256C512 114.6 397.4 0 256 0zM406.6 278.6l-103.1 103.1c-12.5 12.5-32.75 12.5-45.25 0s-12.5-32.75 0-45.25L306.8 288H128C110.3 288 96 273.7 96 256s14.31-32 32-32h178.8l-49.38-49.38c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l103.1 103.1C414.6 241.3 416 251.1 416 256C416 260.9 414.6 270.7 406.6 278.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">Acceder al canal. <\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-c6f020f5\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M256 0C114.6 0 0 114.6 0 256c0 141.4 114.6 256 256 256s256-114.6 256-256C512 114.6 397.4 0 256 0zM406.6 278.6l-103.1 103.1c-12.5 12.5-32.75 12.5-45.25 0s-12.5-32.75 0-45.25L306.8 288H128C110.3 288 96 273.7 96 256s14.31-32 32-32h178.8l-49.38-49.38c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l103.1 103.1C414.6 241.3 416 251.1 416 256C416 260.9 414.6 270.7 406.6 278.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">Crear carpeta.<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-61d98600\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M256 0C114.6 0 0 114.6 0 256c0 141.4 114.6 256 256 256s256-114.6 256-256C512 114.6 397.4 0 256 0zM406.6 278.6l-103.1 103.1c-12.5 12.5-32.75 12.5-45.25 0s-12.5-32.75 0-45.25L306.8 288H128C110.3 288 96 273.7 96 256s14.31-32 32-32h178.8l-49.38-49.38c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l103.1 103.1C414.6 241.3 416 251.1 416 256C416 260.9 414.6 270.7 406.6 278.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">Crear archivo y sincronizar.<\/span><\/div>\n<\/div><\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Crear archivos\" width=\"640\" height=\"480\" src=\"https:\/\/www.youtube.com\/embed\/xw1cBjd1XoM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<div style=\"height:57px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Referencias Bibliogr\u00e1ficas: <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lucero, M. M. (2003). Entre el trabajo colaborativo y el aprendizaje colaborativo. <em>Revista Iberoamericana de Educaci\u00f3n<\/em>, <em>33<\/em>(1), Art. 1. https:\/\/doi.org\/10.35362\/rie3312923<\/p>\n\n\n\n<div style=\"height:70px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><em>El desarrollo de este trabajo por parte de la Universidad de Burgos se ha realizado gracias a las ayudas otorgadas por la Consejer\u00eda de Educaci\u00f3n de la Junta de Castilla y Le\u00f3n a las universidades p\u00fablicas de Castilla y Le\u00f3n para el apoyo al desarrollo de la formaci\u00f3n on-line cofinanciadas por el Fondo Europeo de Desarrollo Regional.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"886\" height=\"151\" src=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2023\/04\/image-8.png\" alt=\"\" class=\"wp-image-5198\" srcset=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2023\/04\/image-8.png 886w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2023\/04\/image-8-300x51.png 300w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2023\/04\/image-8-768x131.png 768w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2023\/04\/image-8-870x148.png 870w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2023\/04\/image-8-390x66.png 390w\" sizes=\"auto, (max-width: 886px) 100vw, 886px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_5094\" class=\"pvc_stats total_only  \" data-element-id=\"5094\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>La creaci\u00f3n de nuevos escenarios de aprendizaje es fundamental para la innovaci\u00f3n educativa. En esta entrada estaremos conociendo propuestas educativas para trabajar con los canales en Teams. <\/p>\n","protected":false},"author":3,"featured_media":5120,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[19],"tags":[54,137],"class_list":["post-5094","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ubucev","tag-elearning","tag-microsoft-teams"],"a3_pvc":{"activated":true,"total_views":96,"today_views":0},"uagb_featured_image_src":{"full":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2023\/04\/Propuestas.jpg",1615,1080,false],"thumbnail":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2023\/04\/Propuestas-150x150.jpg",150,150,true],"medium":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2023\/04\/Propuestas-300x201.jpg",300,201,true],"medium_large":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2023\/04\/Propuestas-768x514.jpg",640,428,true],"large":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2023\/04\/Propuestas-1024x685.jpg",640,428,true],"1536x1536":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2023\/04\/Propuestas-1536x1027.jpg",1536,1027,true],"2048x2048":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2023\/04\/Propuestas.jpg",1615,1080,false],"post-thumbnail":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2023\/04\/Propuestas.jpg",300,201,false],"newspaperly-grid":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2023\/04\/Propuestas.jpg",344,230,false],"newspaperly-slider":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2023\/04\/Propuestas.jpg",850,568,false],"newspaperly-small":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2023\/04\/Propuestas.jpg",269,180,false]},"uagb_author_info":{"display_name":"UBUCEV","author_link":"https:\/\/www3.ubu.es\/ubucevblog\/author\/ubucev\/"},"uagb_comment_info":0,"uagb_excerpt":"La creaci\u00f3n de nuevos escenarios de aprendizaje es fundamental para la innovaci\u00f3n educativa. En esta entrada estaremos conociendo propuestas educativas para trabajar con los canales en Teams.","_links":{"self":[{"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/posts\/5094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/comments?post=5094"}],"version-history":[{"count":53,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/posts\/5094\/revisions"}],"predecessor-version":[{"id":5494,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/posts\/5094\/revisions\/5494"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/media\/5120"}],"wp:attachment":[{"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/media?parent=5094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/categories?post=5094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/tags?post=5094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}