{"id":4254,"date":"2021-04-15T09:12:34","date_gmt":"2021-04-15T09:12:34","guid":{"rendered":"http:\/\/localhost\/?p=4254"},"modified":"2021-11-26T10:37:41","modified_gmt":"2021-11-26T10:37:41","slug":"archivos-del-curso-en-ubuvirtual","status":"publish","type":"post","link":"https:\/\/www3.ubu.es\/ubucevblog\/archivos-del-curso-en-ubuvirtual\/","title":{"rendered":"Archivos del curso en UBUVirtual"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_4254\" class=\"pvc_stats total_only  \" data-element-id=\"4254\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<p class=\"wp-block-paragraph\">En la plataforma UBUVirtual existe la opci\u00f3n \u00ab<strong>archivos del curso<\/strong>\u00bb que, pese a pasar desapercibida en el men\u00fa de acciones, resulta muy \u00fatil en ciertas ocasiones. Veamos sus principales caracter\u00edsticas.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"404\" height=\"370\" src=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2021\/04\/archivoscurso1.jpg\" alt=\"Men\u00fa de acciones - Archivos del curso\" class=\"wp-image-4255\" srcset=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2021\/04\/archivoscurso1.jpg 404w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2021\/04\/archivoscurso1-300x275.jpg 300w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2021\/04\/archivoscurso1-390x357.jpg 390w\" sizes=\"auto, (max-width: 404px) 100vw, 404px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Entrando en \u00abArchivos del curso\u00bb se obtiene un listado de <strong>todos los archivos que est\u00e1n asociados a la asignatura<\/strong>. Si la asignatura tiene cierta antig\u00fcedad, ese listado puede resultar abrumador, ya que en ese primer listado aparecer\u00e1n todos los archivos que existan en la papelera, as\u00ed como los \u00abarchivos del curso heredados\u00bb, entre otros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por tanto, en este punto resulta necesario utilizar los filtros que ofrece la p\u00e1gina. Se pueden <strong>filtrar los resultados<\/strong> por actividades existentes y por tipo de archivo. El listado desplegable \u00abFiltro\u00bb contendr\u00e1 mayor o menor n\u00famero de \u00edtems en funci\u00f3n de los tipos de actividades y recursos existentes en la asignatura. Otro listado desplegable permite filtrar por tipo de archivo, para que solamente se muestren los documentos, im\u00e1genes, archivos de audio, etc.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"239\" src=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2021\/04\/archivoscurso2-1024x239.jpg\" alt=\"\" class=\"wp-image-4256\" srcset=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2021\/04\/archivoscurso2-1024x239.jpg 1024w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2021\/04\/archivoscurso2-300x70.jpg 300w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2021\/04\/archivoscurso2-768x179.jpg 768w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2021\/04\/archivoscurso2-1536x358.jpg 1536w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2021\/04\/archivoscurso2-1170x273.jpg 1170w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2021\/04\/archivoscurso2-870x203.jpg 870w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2021\/04\/archivoscurso2-390x91.jpg 390w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2021\/04\/archivoscurso2.jpg 1601w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Las <strong>columnas del listado<\/strong> reflejan el nombre del archivo, as\u00ed como su tama\u00f1o y su tipo. Tambi\u00e9n se especifica el Componente del curso al cual est\u00e1 asignado el archivo (coincide con el primer filtro desplegable comentado anteriormente), su Licencia de uso y el Gestor de subida, que no es otro que el usuario que ha subido cada archivo.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"casos-de-uso-para-archivos-del-curso\">Casos de uso para Archivos del curso<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La finalidad de los archivos del curso es muy variada, y es adaptable a varias necesidades concretas en lo que respecta al mantenimiento del curso\/asignatura. Principalmente: permite <strong>descargar los archivos que se seleccionen<\/strong> (mediante un bot\u00f3n que se localiza al final de la p\u00e1gina) por lo que, combinando esta utilidad con los filtros, se pueden realizar f\u00e1cilmente algunas operaciones:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Seleccionando <strong>Recurso<\/strong> se pueden listar y descargar todos los archivos que se han subido a la asignatura mediante la opci\u00f3n \u00abA\u00f1adir actividad o recurso\u00bb.<\/li><li>Seleccionando <strong>Tarea<\/strong> se listar\u00e1n todos los documentos que se han incluido en los enunciados de las tareas; y, si se filtra por <strong>Archivos enviados<\/strong>, se obtienen todas las entregas de estudiantes en todas las tareas de la asignatura. Es una forma muy sencilla para guardar un hist\u00f3rico de las tareas realizadas en el curso.<\/li><li>Tambi\u00e9n se pueden obtener las anotaciones-correcciones realizadas en todas las tareas, seleccionando <strong>Anotar PDF<\/strong>. Adem\u00e1s, tambi\u00e9n se puede filtrar por <strong>Archivo de retroalimentaci\u00f3n<\/strong> y obtener un listado con todos ellos.<\/li><li>Si se han adjuntado archivos o im\u00e1genes a alguna pregunta del <a href=\"https:\/\/www3.ubu.es\/ubucevblog\/banco-de-preguntas\/\" target=\"_blank\" rel=\"noreferrer noopener\">Banco de preguntas<\/a>, es posible listar todos esos archivos y descargar los que se seleccionen. Tan s\u00f3lo hace falta filtrar por <strong>Pregunta<\/strong> o por tipos concretos: <strong>Arrastrar y soltar marcadores<\/strong>, <strong>Emparejamiento<\/strong>, etc.<\/li><li>Otro caso de uso permite filtrar por <strong>Foro<\/strong> y as\u00ed obtener todos los archivos que se hayan subido a los foros de la asignatura, sin necesidad de entrar individualmente a cada tema de cada foro.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Seleccionando cualquiera de los archivos que se obtienen, es posible tambi\u00e9n revisar y <strong>gestionar las licencias de uso<\/strong> de los mismos. Para ello existe un bot\u00f3n al final de la p\u00e1gina que permite hacer cambios a varios archivos de una vez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n, y de un primer vistazo, se puede comprobar <strong>qui\u00e9n ha subido cada archivo<\/strong>: es el usuario que aparece en la columna Gestor de ficheros.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><em>El desarrollo de este trabajo por parte de la Universidad de Burgos se ha realizado gracias a las ayudas otorgadas por la Consejer\u00eda de Educaci\u00f3n de la Junta de Castilla y Le\u00f3n a las universidades p\u00fablicas de Castilla y Le\u00f3n para el apoyo al desarrollo de la formaci\u00f3n on-line cofinanciadas por el Fondo Europeo de Desarrollo Regional.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"679\" height=\"116\" src=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2021\/11\/Logos.png\" alt=\"\" class=\"wp-image-4432\" srcset=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2021\/11\/Logos.png 679w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2021\/11\/Logos-300x51.png 300w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2021\/11\/Logos-390x67.png 390w\" sizes=\"auto, (max-width: 679px) 100vw, 679px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_4254\" class=\"pvc_stats total_only  \" data-element-id=\"4254\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>Existe una opci\u00f3n para ver y gestionar los archivos que est\u00e1n asociados a un curso o asignatura en UBUVirtual<\/p>\n","protected":false},"author":3,"featured_media":4258,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[21],"tags":[35],"class_list":["post-4254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ubuvirtual","tag-ubuvirtual"],"a3_pvc":{"activated":true,"total_views":249,"today_views":0},"uagb_featured_image_src":{"full":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2021\/04\/archivos-del-curso.jpg",750,500,false],"thumbnail":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2021\/04\/archivos-del-curso-150x150.jpg",150,150,true],"medium":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2021\/04\/archivos-del-curso-300x200.jpg",300,200,true],"medium_large":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2021\/04\/archivos-del-curso.jpg",640,427,false],"large":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2021\/04\/archivos-del-curso.jpg",640,427,false],"1536x1536":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2021\/04\/archivos-del-curso.jpg",750,500,false],"2048x2048":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2021\/04\/archivos-del-curso.jpg",750,500,false],"post-thumbnail":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2021\/04\/archivos-del-curso.jpg",300,200,false],"newspaperly-grid":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2021\/04\/archivos-del-curso.jpg",345,230,false],"newspaperly-slider":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2021\/04\/archivos-del-curso.jpg",750,500,false],"newspaperly-small":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2021\/04\/archivos-del-curso.jpg",270,180,false]},"uagb_author_info":{"display_name":"UBUCEV","author_link":"https:\/\/www3.ubu.es\/ubucevblog\/author\/ubucev\/"},"uagb_comment_info":0,"uagb_excerpt":"Existe una opci\u00f3n para ver y gestionar los archivos que est\u00e1n asociados a un curso o asignatura en UBUVirtual","_links":{"self":[{"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/posts\/4254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/comments?post=4254"}],"version-history":[{"count":4,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/posts\/4254\/revisions"}],"predecessor-version":[{"id":4444,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/posts\/4254\/revisions\/4444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/media\/4258"}],"wp:attachment":[{"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/media?parent=4254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/categories?post=4254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/tags?post=4254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}