{"id":3468,"date":"2020-06-25T14:13:27","date_gmt":"2020-06-25T14:13:27","guid":{"rendered":"http:\/\/localhost\/?p=3468"},"modified":"2020-06-30T07:40:21","modified_gmt":"2020-06-30T07:40:21","slug":"blended-learning","status":"publish","type":"post","link":"https:\/\/www3.ubu.es\/ubucevblog\/blended-learning\/","title":{"rendered":"Blended learning, dise\u00f1ar el curso en una posible modalidad mixta"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_3468\" class=\"pvc_stats total_only  \" data-element-id=\"3468\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<p class=\"wp-block-paragraph\">El semestre ya ha llegado a su fin. La labor docente ha sido un pilar fundamental durante esta etapa, ahora nos toca reflexionar sobre lo aprendido y mirar hacia el pr\u00f3ximo curso. S\u00ed, y tambi\u00e9n descansar. \ud83d\ude00 Aunque a\u00fan hay dudas sobre c\u00f3mo contextualizar la realidad del pr\u00f3ximo curso (blended learning, online&#8230;) nos queda la <strong>anticipaci\u00f3n y el sentido com\u00fan.<\/strong> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pese a que hay algunas limitaciones, tales como que no sabemos c\u00f3mo ser\u00e1 el inicio ni el final del pr\u00f3ximo semestre (entre otras), s\u00ed podemos adoptar un marco de actuaci\u00f3n dentro de la responsabilidad docente, como es el de hacer lo posible para que <strong>nuestro alumnado consiga los objetivos del curso<\/strong>. <\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Blended learning<\/h3>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Poder dise\u00f1ar la propuesta educativa del pr\u00f3ximo semestre a partir de una hip\u00f3tesis de no presencialidad y que tambi\u00e9n se pueda llevar a cabo presencialmente, va a requerir de <strong>planificaci\u00f3n y algo de creatividad docente<\/strong>. El <strong>blended learning<\/strong> (b-learning), tambi\u00e9n llamado modalidad mixta o h\u00edbrida, es un escenario posible y queremos dar algunas orientaciones para prever las situaciones potencialmente h\u00edbridas que se pueden dar.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Evaluar-las-Tareas-en-UBUVirtual-2.png\" alt=\"\" class=\"wp-image-3502\" width=\"375\" height=\"250\" srcset=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Evaluar-las-Tareas-en-UBUVirtual-2.png 750w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Evaluar-las-Tareas-en-UBUVirtual-2-300x200.png 300w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Evaluar-las-Tareas-en-UBUVirtual-2-270x180.png 270w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Evaluar-las-Tareas-en-UBUVirtual-2-390x260.png 390w\" sizes=\"auto, (max-width: 375px) 100vw, 375px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Esta modalidad formativa responde a situaciones de ense\u00f1anza en las que se pueden determinar en qu\u00e9 momentos habr\u00e1 partes presenciales y no presenciales que configuran el curso. Aunque en este caso, hay que matizarlo, puesto que nos vemos ante una situaci\u00f3n en la que hemos de dise\u00f1ar ante una posible parada de las clases presenciales, <strong>s\u00ed<\/strong> <strong>podemos imaginarnos c\u00f3mo ser\u00edan nuestras clases presenciales y en l\u00ednea<\/strong>.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/blended.png\" alt=\"\" class=\"wp-image-3471\" width=\"351\" height=\"289\" srcset=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/blended.png 701w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/blended-300x247.png 300w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/blended-390x321.png 390w\" sizes=\"auto, (max-width: 351px) 100vw, 351px\" \/><\/figure><\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Dise\u00f1ar el pr\u00f3ximo curso<\/h3>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hemos de hacer un <a aria-label=\"undefined (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www3.ubu.es\/ubucevblog\/elementos-clave-curso-en-linea\/\" target=\"_blank\" rel=\"noreferrer noopener\">dise\u00f1o de nuestra asignatura <\/a>orientado a la prevenci\u00f3n<\/strong>. Esto permitir\u00e1 continuar vinculados al aprendizaje de una manera m\u00e1s normalizada y planificada, en el caso de que se diera una situaci\u00f3n de aprendizaje <a aria-label=\"undefined (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www3.ubu.es\/ubucevblog\/e-learning-caracteristicas\/\" target=\"_blank\" rel=\"noreferrer noopener\">completamente online<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pensar en las secuencias did\u00e1cticas, gestionar las comunicaciones entre docentes y alumnado y entre los propios alumnos, la colaboraci\u00f3n entre ellos y proponer encuentros presenciales flexibles, los cuales sigan con su objetivo con presencia f\u00edsica o sin ella. Para ello, la asincron\u00eda, es tu gran aliada ya que permite la flexibilidad en el espacio y el tiempo.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Algunas claves<\/h3>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Es un reto, lo sabemos, por ello damos algunas claves que pueden servir para planificarnos:<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Planificaci\u00f3n:<\/h4>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>En lugar de dise\u00f1ar por un lado los momentos presenciales y por otro los de no presencialidad, se trata de <strong>pensar en todas las actividades y contenidos como un continuo<\/strong>. De forma que cuando convenga hacer virtualidad, sea f\u00e1cil, promoviendo la flexibilidad.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>Buscar <strong>la esencia de las competencias que queremos trabajar<\/strong> en nuestras asignaturas. \u00bfCu\u00e1les son los objetivos primordiales que tiene que conseguir nuestro alumnado?<\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Evaluar-las-Tareas-en-UBUVirtual-3.png\" alt=\"\" class=\"wp-image-3505\" width=\"375\" height=\"250\" srcset=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Evaluar-las-Tareas-en-UBUVirtual-3.png 750w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Evaluar-las-Tareas-en-UBUVirtual-3-300x200.png 300w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Evaluar-las-Tareas-en-UBUVirtual-3-270x180.png 270w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Evaluar-las-Tareas-en-UBUVirtual-3-390x260.png 390w\" sizes=\"auto, (max-width: 375px) 100vw, 375px\" \/><\/figure><\/div>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Piensa desde una \u00f3ptica digital<\/strong>. Hay muchas actividades que se pueden poner en pr\u00e1ctica online, <a aria-label=\"undefined (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www3.ubu.es\/ubucevblog\/compartir-onedrive\/\" target=\"_blank\" rel=\"noreferrer noopener\">tanto individual como en grupo<\/a>, casos pr\u00e1cticos, actividades de conocimientos previos, ejercicios de aplicaci\u00f3n pr\u00e1ctica, debates, juegos de rol virtuales, proyectos, escape rooms, ejercicios de s\u00edntesis, etc. El criterio para definir una u otra depender\u00e1 del objetivo a conseguir y las posibilidades de interacci\u00f3n (s\u00edncrona\/as\u00edncrona).<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Es el estudiante quien debe apropiarse del aprendizaje<\/strong>. Dise\u00f1ar la asignatura en base a esta perspectiva ayudar\u00e1 a crear y organizar las actividades de aprendizaje con el estudiante en el centro del aprendizaje.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>Elaborar un <strong>plan B de las sesiones presenciales<\/strong>, de modo que sean reversibles en el caso de que finalmente tengan que desarrollarse de manera online. Es importante conservar el objetivo, pero cambiando el m\u00e9todo y mediando la actividad con las <a aria-label=\"undefined (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www3.ubu.es\/ubucevblog\/office-365\/\" target=\"_blank\" rel=\"noreferrer noopener\">herramientas tecnol\u00f3gicas<\/a> de  Universidad. Incluyendo&nbsp;por ejemplo; contenido compartido de forma digital, videoconferencias, sesiones en l\u00ednea, salas de chat, <a aria-label=\"undefined (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www3.ubu.es\/ubucevblog\/foros-en-ubuvirtual\/\" target=\"_blank\" rel=\"noreferrer noopener\">foros evaluables o sin evaluar<\/a>, podcast o audios explicativos, pizarras digitales, documentos colaborativos, etc.<\/li><\/ul>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Comunicaci\u00f3n:<\/h4>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>Aprovecha los <strong>canales de comunicaci\u00f3n de la <\/strong><a href=\"https:\/\/www3.ubu.es\/ubucevblog\/como-resolver-dudas-y-supervisar-un-examen-con-ms-teams\/\" target=\"_blank\" aria-label=\"undefined (abre en una nueva pesta\u00f1a)\" rel=\"noreferrer noopener\"><strong>plataforma<\/strong> <strong>UBUVirtual<\/strong><\/a> y de la Universidad para continuar con la comunicaci\u00f3n y el aprendizaje.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Combina sincron\u00eda y asincron\u00eda<\/strong>, aprovechando las potencialidades de cada una de ellas.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Practica en las sesiones presenciales <\/strong>c\u00f3mo utilizar las <a aria-label=\"undefined (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www3.ubu.es\/ubucevblog\/herramienta-ubuvirtual-mas-adecuada\/\" target=\"_blank\" rel=\"noreferrer noopener\">herramientas<\/a> de un entorno online y c\u00f3mo organizar el trabajo de los estudiantes. Facilitar\u00e1 los cambios de entorno de una forma fluida.<\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Evaluar-las-Tareas-en-UBUVirtual-5.png\" alt=\"\" class=\"wp-image-3512\" width=\"375\" height=\"250\" srcset=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Evaluar-las-Tareas-en-UBUVirtual-5.png 750w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Evaluar-las-Tareas-en-UBUVirtual-5-300x200.png 300w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Evaluar-las-Tareas-en-UBUVirtual-5-270x180.png 270w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Evaluar-las-Tareas-en-UBUVirtual-5-390x260.png 390w\" sizes=\"auto, (max-width: 375px) 100vw, 375px\" \/><\/figure><\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Evaluaci\u00f3n:<\/h4>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Apuesta por la<\/strong> <strong><a aria-label=\"undefined (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www3.ubu.es\/ubucevblog\/seguimiento-trabajos\/\" target=\"_blank\" rel=\"noreferrer noopener\">evaluaci\u00f3n continua y formativa<\/a><\/strong>. Prop\u00f3n <strong>varios procedimientos de evaluaci\u00f3n a lo largo del semestre, con varios pesos<\/strong>. En lugar de centralizar todo el peso en una o dos actividades de mayor ponderaci\u00f3n.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>Utiliza la <strong>autoevaluaci\u00f3n, la coevaluaci\u00f3n y la heteroevaluaci\u00f3n<\/strong>. Aprovecha esos momentos para dar <strong><a aria-label=\"undefined (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/universidaddeburgos-my.sharepoint.com\/personal\/mariapm_ubu_es\/_layouts\/15\/onedrive.aspx?id=%2Fpersonal%2Fmariapm%5Fubu%5Fes%2FDocuments%2FUBUCEV%2FCONTINUIDAD%5FACTIVIDAD%5FCOVID%5F19%2FCORREGIR%20TAREAS%20EN%20UBUVIRTUAL%2Epdf&amp;parent=%2Fpersonal%2Fmariapm%5Fubu%5Fes%2FDocuments%2FUBUCEV%2FCONTINUIDAD%5FACTIVIDAD%5FCOVID%5F19&amp;originalPath=aHR0cHM6Ly91bml2ZXJzaWRhZGRlYnVyZ29zLW15LnNoYXJlcG9pbnQuY29tLzpiOi9nL3BlcnNvbmFsL21hcmlhcG1fdWJ1X2VzL0VhSDRRQVhLU214S2hhcU1oaUh4R01zQjlIeHlhaERBRlF1VlpGQnQ3SUxTeVE_cnRpbWU9QnFseWlWRFcxMGc\" target=\"_blank\" rel=\"noreferrer noopener\">feedback personalizado<\/a><\/strong> tambi\u00e9n. Piensa que no todo el feedback ha de venir del docente, la <strong>retroalimentaci\u00f3n entre los propios alumnos es una oportunidad para el aprendizaje muy valiosa<\/strong>.<\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Evaluar-las-Tareas-en-UBUVirtual-4.png\" alt=\"\" class=\"wp-image-3510\" width=\"375\" height=\"250\" srcset=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Evaluar-las-Tareas-en-UBUVirtual-4.png 750w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Evaluar-las-Tareas-en-UBUVirtual-4-300x200.png 300w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Evaluar-las-Tareas-en-UBUVirtual-4-270x180.png 270w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Evaluar-las-Tareas-en-UBUVirtual-4-390x260.png 390w\" sizes=\"auto, (max-width: 375px) 100vw, 375px\" \/><\/figure><\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Es cierto que no sabemos en qu\u00e9 momento ni cu\u00e1nta duraci\u00f3n puede llegar a darse la modalidad online o presencial en el nuevo curso, lo que s\u00ed sabemos es que podemos hacerlo y que nuestro nivel de adaptaci\u00f3n y manejo de la situaci\u00f3n es cada vez mayor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuanto m\u00e1s lo preparemos, menos imprevistos nos encontraremos en una situaci\u00f3n de contingencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Feliz verano.\u2600<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_3468\" class=\"pvc_stats total_only  \" data-element-id=\"3468\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>Dise\u00f1ar el pr\u00f3ximo curso requiere planificaci\u00f3n y creatividad, algunas claves para llevarlo mejor.<\/p>\n","protected":false},"author":3,"featured_media":3473,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[19],"tags":[105,107,106,66],"class_list":["post-3468","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ubucev","tag-blended-learning","tag-diseno-instruccional","tag-docencia-en-linea","tag-metodologias"],"a3_pvc":{"activated":true,"total_views":238,"today_views":0},"uagb_featured_image_src":{"full":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Blended-learning-dise\u00f1ar-el-pr\u00f3ximo-curso.png",750,500,false],"thumbnail":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Blended-learning-dise\u00f1ar-el-pr\u00f3ximo-curso-150x150.png",150,150,true],"medium":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Blended-learning-dise\u00f1ar-el-pr\u00f3ximo-curso-300x200.png",300,200,true],"medium_large":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Blended-learning-dise\u00f1ar-el-pr\u00f3ximo-curso.png",640,427,false],"large":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Blended-learning-dise\u00f1ar-el-pr\u00f3ximo-curso.png",640,427,false],"1536x1536":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Blended-learning-dise\u00f1ar-el-pr\u00f3ximo-curso.png",750,500,false],"2048x2048":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Blended-learning-dise\u00f1ar-el-pr\u00f3ximo-curso.png",750,500,false],"post-thumbnail":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Blended-learning-dise\u00f1ar-el-pr\u00f3ximo-curso.png",300,200,false],"newspaperly-grid":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Blended-learning-dise\u00f1ar-el-pr\u00f3ximo-curso.png",345,230,false],"newspaperly-slider":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Blended-learning-dise\u00f1ar-el-pr\u00f3ximo-curso.png",750,500,false],"newspaperly-small":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/06\/Blended-learning-dise\u00f1ar-el-pr\u00f3ximo-curso.png",270,180,false]},"uagb_author_info":{"display_name":"UBUCEV","author_link":"https:\/\/www3.ubu.es\/ubucevblog\/author\/ubucev\/"},"uagb_comment_info":0,"uagb_excerpt":"Dise\u00f1ar el pr\u00f3ximo curso requiere planificaci\u00f3n y creatividad, algunas claves para llevarlo mejor.","_links":{"self":[{"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/posts\/3468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/comments?post=3468"}],"version-history":[{"count":44,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/posts\/3468\/revisions"}],"predecessor-version":[{"id":3520,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/posts\/3468\/revisions\/3520"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/media\/3473"}],"wp:attachment":[{"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/media?parent=3468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/categories?post=3468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/tags?post=3468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}