{"id":2892,"date":"2020-03-30T08:24:52","date_gmt":"2020-03-30T08:24:52","guid":{"rendered":"http:\/\/localhost\/?p=2892"},"modified":"2020-03-30T08:24:55","modified_gmt":"2020-03-30T08:24:55","slug":"como-imparte-su-asignatura-online-raul-marticorena","status":"publish","type":"post","link":"https:\/\/www3.ubu.es\/ubucevblog\/como-imparte-su-asignatura-online-raul-marticorena\/","title":{"rendered":"\u00bfC\u00f3mo imparte su asignatura online Ra\u00fal Marticorena?"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_2892\" class=\"pvc_stats total_only  \" data-element-id=\"2892\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<div class=\"wp-block-media-text alignwide has-background has-very-light-gray-background-color\" style=\"grid-template-columns:19% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"181\" height=\"181\" src=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/0.jpg\" alt=\"\" class=\"wp-image-2893\" srcset=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/0.jpg 181w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/0-150x150.jpg 150w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/0-75x75.jpg 75w\" sizes=\"auto, (max-width: 181px) 100vw, 181px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-medium-font-size wp-block-paragraph\"> <\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Ra\u00fal Marticorena<\/strong>, docente del grado online en Ingenier\u00eda Inform\u00e1tica de la Universidad de Burgos,&nbsp;<strong>nos cuenta su experiencia<\/strong>&nbsp;despu\u00e9s de varios a\u00f1os impartiendo su asignatura online. <\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">A continuaci\u00f3n, os indico c\u00f3mo he\nplanteado una asignatura de programaci\u00f3n (Metodolog\u00eda de la Programaci\u00f3n de 2\u00ba\nGrado de Ingenier\u00eda Inform\u00e1tica) en la modalidad online. La asignatura se lleva\nimpartiendo desde el curso 2015-2016 (5\u00aa edici\u00f3n).<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h1 class=\"wp-block-heading\">\u00bfC\u00f3mo organizo mi asignatura?<\/h1>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"134\" src=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interactividad-1024x134.jpg\" alt=\"\" class=\"wp-image-2727\" srcset=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interactividad-1024x134.jpg 1024w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interactividad-300x39.jpg 300w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interactividad-768x100.jpg 768w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interactividad-1536x201.jpg 1536w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interactividad-1170x153.jpg 1170w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interactividad-870x114.jpg 870w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interactividad-390x51.jpg 390w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interactividad.jpg 1707w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El primer d\u00eda de clase cuelgo un <strong>calendario\ncon la programaci\u00f3n tentativa<\/strong> de la asignatura con todo lo que se va a\nhacer: teor\u00eda, pr\u00e1cticas y ex\u00e1menes\/entregas obligatorias. Es muy importante\nporque sirve de <strong>br\u00fajula<\/strong> a lo largo del curso (tanto para los alumnos\ncomo profesores).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La asignatura se organiza en <strong>semanas<\/strong>,\naunque Moodle tambi\u00e9n nos deja organizarla por temas. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto es una elecci\u00f3n un poco <strong>personal<\/strong>.\nEn particular yo trabajo por semanas en online, y hago una peque\u00f1a \u201ctrampa\u201d, transformando\nlas \u00faltimas semanas en temas de teor\u00eda (simplemente cambiando la etiqueta de\ntexto ?).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El <strong>lunes de cada semana<\/strong>\nles env\u00edo las <strong>instrucciones<\/strong> al foro, de lo que se espera que hagan esa\nsemana, tanto a <strong>nivel pr\u00e1ctico<\/strong>, como lo que deben mirar y estudiar antes\na <strong>nivel te\u00f3rico<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les aviso o recuerdo en dicho\nmensaje, si hay alguna entrega de autoevaluaci\u00f3n o de evaluaci\u00f3n pr\u00f3ximamente.<\/p>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h1 class=\"wp-block-heading\">\u00bfQu\u00e9 materiales utilizo?<\/h1>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"134\" src=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/examenes-1024x134.jpg\" alt=\"\" class=\"wp-image-2787\" srcset=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/examenes-1024x134.jpg 1024w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/examenes-300x39.jpg 300w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/examenes-768x100.jpg 768w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/examenes-1536x201.jpg 1536w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/examenes-1170x153.jpg 1170w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/examenes-870x114.jpg 870w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/examenes-390x51.jpg 390w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/examenes.jpg 1707w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Genero <strong>v\u00eddeos<\/strong> narrando\ndiapositivas, y a\u00f1adiendo efectos visuales como zooms, focos, notas\nexplicativas adicionales, etc. con todas las clases relativas a la teor\u00eda. Esto\nles da libertad para acceder a la clase de teor\u00eda cuando quieran.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para ello se puede utilizar software\ncomo <a href=\"https:\/\/atomisystems.com\/activepresenter\/\">ActivePresenter<\/a>, aunque\nel proceso es lento y laborioso. Si no se requiere hacer v\u00eddeos muy elaborados\no \u201cperfectos\u201d, ahora contamos con <a href=\"https:\/\/www.elearningmedia.es\/soluciones\/video-para-educacion\/kaltura\">Kaltura<\/a>\nintegrado en UBUVirtual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para las sesiones pr\u00e1cticas les\ndejo unos <strong>guiones de pr\u00e1cticas<\/strong> con los pasos <strong>detallados<\/strong> a\nrealizar y <strong>ejercicios planteados<\/strong> (documentos .pdf). Si la explicaci\u00f3n es\ncompleja y lo requiere, aporto adem\u00e1s alg\u00fan <em>screencast<\/em> de factura propia,\no de terceros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adicionalmente al ser una\nasignatura de programaci\u00f3n, tambi\u00e9n les suelo dejar <strong>c\u00f3digos de ejemplo y test\nunitarios<\/strong>. Aunque estos son materiales muy espec\u00edficos de este campo.<\/p>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h1 class=\"wp-block-heading\">\u00bfC\u00f3mo tienen que trabajar?<\/h1>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"134\" src=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/tareas-1024x134.jpg\" alt=\"\" class=\"wp-image-2900\" srcset=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/tareas-1024x134.jpg 1024w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/tareas-300x39.jpg 300w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/tareas-768x100.jpg 768w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/tareas-1536x201.jpg 1536w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/tareas-1170x153.jpg 1170w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/tareas-870x114.jpg 870w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/tareas-390x51.jpg 390w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/tareas.jpg 1707w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Deben intentar realizar el <strong>guion\nde pr\u00e1cticas <\/strong>de la semana, aplicando los conocimientos vistos en teor\u00eda con\nlos <strong>v\u00eddeos<\/strong>. Para comprobar su trabajo, se suele solicitar en el guion realizar\nuna <strong>entrega <\/strong>a la siguiente semana en una <strong>tarea<\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dichas <strong>tareas<\/strong> se corrigen\npor el profesor, indicando como <strong><em>feedback<\/em><\/strong> personalizado los errores\nencontrados. Son actividades formativas que no cuentan para nota, pero les\nayuda a ir corrigiendo errores y mejorar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dado que los errores se repiten\nentre el alumnado, se elabora un <strong>documento<\/strong> <strong>de errores m\u00e1s frecuentes\n(un FAQ)<\/strong> y se deja a su disposici\u00f3n para consulta posterior de todos.<\/p>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h1 class=\"wp-block-heading\">\u00bfC\u00f3mo es la interacci\u00f3n?<\/h1>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"134\" src=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interaccion-1-1024x134.jpg\" alt=\"\" class=\"wp-image-2739\" srcset=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interaccion-1-1024x134.jpg 1024w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interaccion-1-300x39.jpg 300w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interaccion-1-768x100.jpg 768w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interaccion-1-1536x201.jpg 1536w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interaccion-1-1170x153.jpg 1170w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interaccion-1-870x114.jpg 870w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interaccion-1-390x51.jpg 390w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interaccion-1.jpg 1707w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Para cada tema, se deja\ndisponible un <strong>foro de preguntas<\/strong>, para ir resolviendo las <strong>dudas<\/strong>.\nTanto de teor\u00eda como en la realizaci\u00f3n del guion de pr\u00e1cticas que toque esa semana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si el problema no se puede\nresolver en los foros entre todos, o es muy particular o imposible de resolver\nde forma escrita en el foro, se puede redirigir a <strong>una tutor\u00eda personal\nonline<\/strong> a realizar con <strong>Skype Empresarial, <\/strong>donde adem\u00e1s se puede<strong>\ncompartir el escritorio <\/strong>o utilizar la<strong> pizarra integrada.<\/strong><\/p>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h1 class=\"wp-block-heading\">\u00bfC\u00f3mo eval\u00fao?<\/h1>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"134\" src=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/EVALUACION-1024x134.jpg\" alt=\"\" class=\"wp-image-2737\" srcset=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/EVALUACION-1024x134.jpg 1024w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/EVALUACION-300x39.jpg 300w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/EVALUACION-768x100.jpg 768w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/EVALUACION-1536x201.jpg 1536w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/EVALUACION-1170x153.jpg 1170w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/EVALUACION-870x114.jpg 870w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/EVALUACION-390x51.jpg 390w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/EVALUACION.jpg 1707w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En primer lugar, habilito una\nsemana\/tema que llamo \u201cPrimera convocatoria\u201d y otro para \u201cSegunda\nconvocatoria\u201d. En esa semana o tema, se colocan <strong>todas las pruebas de\nevaluaci\u00f3n sumativa<\/strong> que s\u00ed cuentan para nota. Esto les ayuda a <strong>localizar<\/strong>\nlas pruebas de evaluaci\u00f3n f\u00e1cilmente, y deber\u00eda coincidir con la estructura del\n<strong>libro de calificaciones<\/strong> y <strong>gu\u00eda docente.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esta asignatura se trabaja con\naprendizaje basado en proyectos (un juego programado) con dos entregas, a\ntrav\u00e9s de <strong>tareas Moodle<\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para comprobar la autor\u00eda y que\nse pueda sumar la nota de los proyectos, se realiza una <strong>defensa oral individual\nde cada trabajo una vez corregido el proyecto, <\/strong>a trav\u00e9s de la sala virtual\ncon Skype Empresarial, cuyo horario se fija con una <strong>consulta<\/strong> de Moodle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta <strong>defensa oral<\/strong> dura uno\n30 minutos y el alumno\/a debe ser capaz de responder a cuestiones sobre su\npropio trabajo. <strong>Evita el plagio o copia.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, se realizan dos ex\u00e1menes\nen <strong>fecha y hora fijada desde el inicio del curso<\/strong>, con:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Cuestionarios Moodle con SMOWL<\/strong> para\naquellas pruebas de corte m\u00e1s te\u00f3rico<\/li><li><strong>Cuestionarios Moodle con vigilancia a trav\u00e9s\nde Skype Empresarial<\/strong> para pruebas m\u00e1s pr\u00e1cticas, en la que los alumnos\ntengan que utilizar entornos m\u00e1s complejos de programaci\u00f3n y material adicional\nde apoyo (c\u00f3digos fuente, etc.).<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">En los <strong>cuestionarios<\/strong> se\ncombinan preguntas de tipo <strong>respuesta m\u00faltiple<\/strong> con preguntas de tipo <strong>ensayo,<\/strong>\no en mi caso, incluso subida de ficheros adjuntos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En todas las pruebas realizadas,\nse entrega una <strong>retroalimentaci\u00f3n<\/strong> con los errores detectados justificando\nla calificaci\u00f3n (bien en la tarea o cuestionario). Las calificaciones se\npublican tambi\u00e9n en el <strong>calificador<\/strong> para que el alumno tenga claro su\n\u201clibro de calificaciones\u201d.<\/p>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h1 class=\"wp-block-heading\">Otras recomendaciones<\/h1>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>No se puede hacer todo esto de golpe. <\/strong>Hay\nque ir incorporando distintos elementos a la asignatura, o lo que sean m\u00e1s <strong>necesarios<\/strong>\no <strong>\u00fatiles<\/strong>, de uno en uno. Lo aqu\u00ed indicado, es fruto de varios a\u00f1os de\nevoluci\u00f3n en la asignatura <strong>con aciertos y fallos. <\/strong>Cada asignatura es\ndiferente, no en todas mis asignaturas utilizo este mismo sistema.<\/li><li><strong>Intenta dar respuesta a las cuestiones que se\nplanteen en un plazo razonable y seg\u00fan su urgencia.<\/strong> No se trata de ser un\n\u201ccall center\u201d dando respuestas en tiempo real, tampoco es recomendable, ni\nfactible, pero tampoco no contestar.<\/li><li><strong>Adicionalmente, se pueden realizar encuestas\nde seguimiento para ir evaluando c\u00f3mo est\u00e1 funcionando la asignatura. <\/strong>Moodle\nintegra una actividad de <strong>encuesta<\/strong> que puede ser <strong>an\u00f3nima<\/strong>. Esto es\nparticularmente \u00fatil las primeras veces que se imparte, hasta que se estabiliza\nla asignatura.<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_2892\" class=\"pvc_stats total_only  \" data-element-id=\"2892\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>Ra\u00fal Marticorena, docente del grado online en Inform\u00e1tica de la Universidad de Burgos, nos cuenta su experiencia despu\u00e9s de varios a\u00f1os impartiendo su asignatura online. <\/p>\n","protected":false},"author":3,"featured_media":2897,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-2892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ubucev"],"a3_pvc":{"activated":true,"total_views":269,"today_views":0},"uagb_featured_image_src":{"full":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/experiencias.jpg",750,500,false],"thumbnail":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/experiencias-150x150.jpg",150,150,true],"medium":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/experiencias-300x200.jpg",300,200,true],"medium_large":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/experiencias.jpg",640,427,false],"large":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/experiencias.jpg",640,427,false],"1536x1536":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/experiencias.jpg",750,500,false],"2048x2048":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/experiencias.jpg",750,500,false],"post-thumbnail":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/experiencias.jpg",300,200,false],"newspaperly-grid":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/experiencias.jpg",345,230,false],"newspaperly-slider":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/experiencias.jpg",750,500,false],"newspaperly-small":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/experiencias.jpg",270,180,false]},"uagb_author_info":{"display_name":"UBUCEV","author_link":"https:\/\/www3.ubu.es\/ubucevblog\/author\/ubucev\/"},"uagb_comment_info":0,"uagb_excerpt":"Ra\u00fal Marticorena, docente del grado online en Inform\u00e1tica de la Universidad de Burgos, nos cuenta su experiencia despu\u00e9s de varios a\u00f1os impartiendo su asignatura online.","_links":{"self":[{"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/posts\/2892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/comments?post=2892"}],"version-history":[{"count":9,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/posts\/2892\/revisions"}],"predecessor-version":[{"id":2997,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/posts\/2892\/revisions\/2997"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/media\/2897"}],"wp:attachment":[{"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/media?parent=2892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/categories?post=2892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/tags?post=2892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}