{"id":2714,"date":"2020-03-23T19:26:57","date_gmt":"2020-03-23T19:26:57","guid":{"rendered":"http:\/\/localhost\/?p=2714"},"modified":"2020-03-23T19:27:00","modified_gmt":"2020-03-23T19:27:00","slug":"como-imparte-su-asignatura-online-sergio-perez-castanos","status":"publish","type":"post","link":"https:\/\/www3.ubu.es\/ubucevblog\/como-imparte-su-asignatura-online-sergio-perez-castanos\/","title":{"rendered":"\u00bfC\u00f3mo imparte su asignatura online Sergio P\u00e9rez Casta\u00f1os?"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_2714\" class=\"pvc_stats total_only  \" data-element-id=\"2714\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>\n<div class=\"wp-block-media-text alignfull has-background has-very-light-gray-background-color\" style=\"grid-template-columns:21% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/sergio-perez-casta\u00f1os-1.jpg\" alt=\"\" class=\"wp-image-2755\" srcset=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/sergio-perez-casta\u00f1os-1.jpg 200w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/sergio-perez-casta\u00f1os-1-150x150.jpg 150w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/sergio-perez-casta\u00f1os-1-75x75.jpg 75w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-text-color has-medium-font-size has-very-dark-gray-color wp-block-paragraph\"> <\/p>\n\n\n\n<p class=\"has-text-color has-medium-font-size has-very-dark-gray-color wp-block-paragraph\"><strong>Sergio P\u00e9rez Casta\u00f1os<\/strong>, docente del grado online en Ciencia Pol\u00edtica y Gesti\u00f3n P\u00fablica de la Universidad de Burgos, <strong>nos cuenta su experiencia<\/strong> despu\u00e9s de varios a\u00f1os impartiendo su asignatura online.  <\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\"><strong>\u00bfC\u00d3MO TRABAJO CON LOS ESTUDIANTES?<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"134\" src=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interactividad-1-1024x134.jpg\" alt=\"\" class=\"wp-image-2742\" srcset=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interactividad-1-1024x134.jpg 1024w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interactividad-1-300x39.jpg 300w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interactividad-1-768x100.jpg 768w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interactividad-1-1536x201.jpg 1536w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interactividad-1-1170x153.jpg 1170w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interactividad-1-870x114.jpg 870w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interactividad-1-390x51.jpg 390w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interactividad-1.jpg 1707w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Lo primero es un <strong>cronograma<\/strong>, en donde los estudiantes saben cada semana o semanas <strong>qu\u00e9 elementos del temario vamos desarrollando<\/strong>, as\u00ed como las <strong>pr\u00e1cticas <\/strong>que van a tener que realizar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con cada apertura del tema, adem\u00e1s de notificarlo, tienen unas lecturas que <strong>parten el tema en 3 o 4 apartados<\/strong> generales. De esos apartados, hay un <strong>v\u00eddeo-resumen de los elementos m\u00e1s destacados o complejos.<\/strong> Esos ser\u00edan los elementos que posteriormente ser\u00e1n implementados en los diferentes procesos de evaluaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De esta manera, todos los estudiantes saben <strong>qu\u00e9 tienen que estudiar y de d\u00f3nde<\/strong>. Adem\u00e1s, cuentan de forma preventiva con la explicaci\u00f3n y resoluci\u00f3n de posibles dudas.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\"><strong>\u00bfC\u00d3MO ES LA INTERACCI\u00d3N?<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"134\" src=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interaccion-1-1024x134.jpg\" alt=\"\" class=\"wp-image-2739\" srcset=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interaccion-1-1024x134.jpg 1024w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interaccion-1-300x39.jpg 300w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interaccion-1-768x100.jpg 768w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interaccion-1-1536x201.jpg 1536w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interaccion-1-1170x153.jpg 1170w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interaccion-1-870x114.jpg 870w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interaccion-1-390x51.jpg 390w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/interaccion-1.jpg 1707w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Mi interacci\u00f3n con ellos se da a trav\u00e9s de dos cauces. Por un lado, al menos <strong>dos tutor\u00edas obligatorias a trav\u00e9s del Skype Empresarial.<\/strong> Una se realiza al inicio del curso y la otra en torno a la mitad. Esas las obligatorias. Por supuesto, pueden seguir contactando y concertando <strong>tutor\u00edas <\/strong>tanto como deseen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por el otro lado utilizo los <strong>foros<\/strong>. En el <strong>foro de novedades<\/strong> simplemente les aviso de <strong>elementos novedosos<\/strong> disponibles en la plataforma. En el <strong>foro de Avisos<\/strong> les cuelgo<strong> recordatorios de las entregas de ejercicios <\/strong>o de otras cuestiones ajenas a la asignatura. Finalmente, en el <strong>foro de dudas<\/strong> es en donde se realiza una <strong>gran parte de la interacci\u00f3n<\/strong> tanto con el profesor como entre los y las estudiantes. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De entrada, de nuevo como con los temas, <strong>cada una de las cuestiones m\u00e1s relevantes tiene abierto un hilo en el foro<\/strong> desde el inicio del tema. All\u00ed los propios estudiantes van plasmando problemas. En caso de que los estudiantes me contacten a trav\u00e9s del correo o me comenten dudas en videotutor\u00eda, suelo <strong>postear yo mismo dichas dudas para que se pongan en conocimiento de todos<\/strong> y puedan servir a otros con problemas o cuestiones similares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No regulo otro tipo de interacci\u00f3n\nentre ellos ni tengo entre mis pruebas evaluables trabajos grupales. Con las\nnuevas aulas pretend\u00eda emitir docencia en directo y grabarla para que quedara\nrecogida en la plataforma, pero la situaci\u00f3n no lo ha permitido.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\"><strong>\u00bfC\u00d3MO ES LA EVALUACI\u00d3N?<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"134\" src=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/EVALUACION-1024x134.jpg\" alt=\"\" class=\"wp-image-2737\" srcset=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/EVALUACION-1024x134.jpg 1024w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/EVALUACION-300x39.jpg 300w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/EVALUACION-768x100.jpg 768w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/EVALUACION-1536x201.jpg 1536w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/EVALUACION-1170x153.jpg 1170w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/EVALUACION-870x114.jpg 870w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/EVALUACION-390x51.jpg 390w, https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/EVALUACION.jpg 1707w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La evaluaci\u00f3n consta de varios apartados. Por un lado, <strong>en cada tema los estudiantes tienen cuestionarios de autoevaluaci\u00f3n<\/strong> no obligatorios y no evaluables. Sirven para saber si est\u00e1n avanzando en la l\u00ednea correcta y, adem\u00e1s, sirven para <strong>conocer el estilo de preguntas<\/strong> que pueden aparecer en la prueba te\u00f3rica final.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, tenemos las <strong>pruebas evaluables<\/strong>. Estas constan de <strong>tres pruebas pr\u00e1cticas en donde se construye con lo visto en los temas hasta el que est\u00e1 programada<\/strong>. Adem\u00e1s, hay un <strong>trabajo final <\/strong>que tiene el mismo formato que si se unieran las tres pruebas de evaluaci\u00f3n continua. Gracias al aprendizaje a trav\u00e9s de los errores, garantizo que el desarrollo del trabajo va a ser adecuado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">FEEDBACK<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto al feedback, se utiliza el <strong>sistema de comentarios disponible<\/strong>. Cuando Turnitin lo ten\u00eda activado, he utilizado hasta el comentario de voz. Obviamente, <strong>cada pr\u00e1ctica tiene una r\u00fabrica<\/strong> y los comentarios son sobre esa misma r\u00fabrica. Adem\u00e1s, se aportan elementos de cara a mejorar cuestiones m\u00e1s all\u00e1 del contenido como la presentaci\u00f3n e imagen de los documentos -asignatura estad\u00edstica, de presentaci\u00f3n y comentario de resultados y salidas de SPSS-. De nuevo, este semestre, pretend\u00eda realizar <strong>correcciones en vivo o realizaci\u00f3n de pr\u00e1ctica en vivo<\/strong> gracias a las aulas nuevas, pero ha sido imposible.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">PRUEBA FINAL<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, la <strong>prueba te\u00f3rica de contenidos<\/strong> se hace a trav\u00e9s del <strong>cuestionario de Moodle con el sistema de videovigilancia SMOWL<\/strong>. De nuevo, las personas que han realizado los cuestionarios de autoevaluaci\u00f3n de cada tema no suelen tener problemas para superar la prueba, en la medida de que, aunque m\u00e1s complejizadas, <strong>los contenidos de las preguntas son similares.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_2714\" class=\"pvc_stats total_only  \" data-element-id=\"2714\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>Sergio P\u00e9rez Casta\u00f1os, docente del grado online en Ciencia Pol\u00edtica y Gesti\u00f3n P\u00fablica de la UBU, nos cuenta su experiencia despu\u00e9s de varios a\u00f1os impartiendo su asignatura online.<\/p>\n","protected":false},"author":3,"featured_media":2762,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-2714","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ubucev"],"a3_pvc":{"activated":true,"total_views":145,"today_views":0},"uagb_featured_image_src":{"full":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/EXPERIENCIAS-POLITICAS-1.jpg",750,500,false],"thumbnail":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/EXPERIENCIAS-POLITICAS-1-150x150.jpg",150,150,true],"medium":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/EXPERIENCIAS-POLITICAS-1-300x200.jpg",300,200,true],"medium_large":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/EXPERIENCIAS-POLITICAS-1.jpg",640,427,false],"large":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/EXPERIENCIAS-POLITICAS-1.jpg",640,427,false],"1536x1536":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/EXPERIENCIAS-POLITICAS-1.jpg",750,500,false],"2048x2048":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/EXPERIENCIAS-POLITICAS-1.jpg",750,500,false],"post-thumbnail":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/EXPERIENCIAS-POLITICAS-1.jpg",300,200,false],"newspaperly-grid":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/EXPERIENCIAS-POLITICAS-1.jpg",345,230,false],"newspaperly-slider":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/EXPERIENCIAS-POLITICAS-1.jpg",750,500,false],"newspaperly-small":["https:\/\/www3.ubu.es\/ubucevblog\/wp-content\/uploads\/2020\/03\/EXPERIENCIAS-POLITICAS-1.jpg",270,180,false]},"uagb_author_info":{"display_name":"UBUCEV","author_link":"https:\/\/www3.ubu.es\/ubucevblog\/author\/ubucev\/"},"uagb_comment_info":0,"uagb_excerpt":"Sergio P\u00e9rez Casta\u00f1os, docente del grado online en Ciencia Pol\u00edtica y Gesti\u00f3n P\u00fablica de la UBU, nos cuenta su experiencia despu\u00e9s de varios a\u00f1os impartiendo su asignatura online.","_links":{"self":[{"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/posts\/2714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/comments?post=2714"}],"version-history":[{"count":31,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/posts\/2714\/revisions"}],"predecessor-version":[{"id":2783,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/posts\/2714\/revisions\/2783"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/media\/2762"}],"wp:attachment":[{"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/media?parent=2714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/categories?post=2714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www3.ubu.es\/ubucevblog\/wp-json\/wp\/v2\/tags?post=2714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}